{"id":1776,"date":"2026-04-15T17:35:14","date_gmt":"2026-04-15T15:35:14","guid":{"rendered":"https:\/\/www.inognicasonessunrimorso.org\/blog\/?p=1776"},"modified":"2026-07-15T17:35:27","modified_gmt":"2026-07-15T15:35:27","slug":"materiali-convegno-comitato-internazionalista-alexis-castillo","status":"publish","type":"post","link":"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/","title":{"rendered":"Materiali convegno: Comitato Internazionalista Alexis Castillo"},"content":{"rendered":"\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.inognicasonessunrimorso.org\/blog\/wp-content\/uploads\/sites\/3\/2026\/07\/COMITATO_ALEXIS_CASTILLO.mp3\"><\/audio><\/figure>\n\n\n\n<p>La fase attuale della crisi multidimensionale, strutturale e sistemica del modo di produzione capitalistico \u00e8 attraversata, su scala planetaria, da diversi conflitti -guerreggiati e non &#8211; solo apparentemente scollegati tra loro. Sono la forma concreta, con discontinuit\u00e0 geografica e spaziale, che assume la III Guerra Mondiale in corso. E\u2019 il modo di essere del capitalismo imperialista in crisi senile, votato pi\u00f9 che mai alla distruzione di forze produttive; ma al contempo esprime lo scontro tra due visioni contrapposte non solo delle relazioni internazionali e geopolitiche, ma anche degli assetti internazionali e mondiali in permanente riconfigurazione. Strategia, tattiche, rapporti di forza, dimensione politica, economica e militare dello scontro in atto, sono concetti e fenomeni la cui comprensione e la cui analisi non possono prescindere da un approccio metodologico non \u201cgeopoliticista\u201d, bens\u00ec fondato sulla pi\u00f9 completa e potente cassetta degli attrezzi di cui si possa disporre: la Teoria Marxista della crisi. Le relazioni tra Stati e blocchi, nonch\u00e9 l\u2019evolversi degli eventi nei diversi fronti della III Guerra mondiale, si intersecano e sono attraversati, anche quando l\u2019evidenza assume contorni meno definiti, dalla lotta di classe e dalle lotte di liberazione nazionale e sociale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La fase attuale della crisi multidimensionale, strutturale e sistemica del modo di produzione capitalistico \u00e8 attraversata, su scala planetaria, da diversi conflitti -guerreggiati e non &#8211; solo apparentemente scollegati tra loro. Sono la forma concreta, con discontinuit\u00e0 geografica e spaziale, che assume la III Guerra Mondiale in corso. E\u2019 il modo di essere del capitalismo&hellip;&nbsp;<a href=\"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/\" class=\"\" rel=\"bookmark\">Leggi tutto &raquo;<span class=\"screen-reader-text\">Materiali convegno: Comitato Internazionalista Alexis Castillo<\/span><\/a><\/p>\n","protected":false},"author":17,"featured_media":1702,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"center","neve_meta_author_avatar":"","neve_post_elements_order":"[\"title\",\"meta\",\"content\",\"tags\"]","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-dalla-rete"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Materiali convegno: Comitato Internazionalista Alexis Castillo - In ogni caso nessun rimorso<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Materiali convegno: Comitato Internazionalista Alexis Castillo - In ogni caso nessun rimorso\" \/>\n<meta property=\"og:description\" content=\"La fase attuale della crisi multidimensionale, strutturale e sistemica del modo di produzione capitalistico \u00e8 attraversata, su scala planetaria, da diversi conflitti -guerreggiati e non &#8211; solo apparentemente scollegati tra loro. Sono la forma concreta, con discontinuit\u00e0 geografica e spaziale, che assume la III Guerra Mondiale in corso. E\u2019 il modo di essere del capitalismo&hellip;&nbsp;Leggi tutto &raquo;Materiali convegno: Comitato Internazionalista Alexis Castillo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/\" \/>\n<meta property=\"og:site_name\" content=\"In ogni caso nessun rimorso\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-15T15:35:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T15:35:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.inognicasonessunrimorso.org\/blog\/wp-content\/uploads\/sites\/3\/2026\/07\/COPERTINA.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"carlo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"carlo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/\",\"url\":\"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/\",\"name\":\"Materiali convegno: Comitato Internazionalista Alexis Castillo - In ogni caso nessun rimorso\",\"isPartOf\":{\"@id\":\"https:\/\/www.inognicasonessunrimorso.org\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.inognicasonessunrimorso.org\/blog\/wp-content\/uploads\/sites\/3\/2026\/07\/COPERTINA.jpeg\",\"datePublished\":\"2026-04-15T15:35:14+00:00\",\"dateModified\":\"2026-07-15T15:35:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.inognicasonessunrimorso.org\/blog\/#\/schema\/person\/12bbdd71594a9993b4141453c7197202\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/#primaryimage\",\"url\":\"https:\/\/www.inognicasonessunrimorso.org\/blog\/wp-content\/uploads\/sites\/3\/2026\/07\/COPERTINA.jpeg\",\"contentUrl\":\"https:\/\/www.inognicasonessunrimorso.org\/blog\/wp-content\/uploads\/sites\/3\/2026\/07\/COPERTINA.jpeg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.inognicasonessunrimorso.org\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Materiali convegno: Comitato Internazionalista Alexis Castillo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.inognicasonessunrimorso.org\/blog\/#website\",\"url\":\"https:\/\/www.inognicasonessunrimorso.org\/blog\/\",\"name\":\"In ogni caso nessun rimorso\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.inognicasonessunrimorso.org\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.inognicasonessunrimorso.org\/blog\/#\/schema\/person\/12bbdd71594a9993b4141453c7197202\",\"name\":\"carlo\",\"url\":\"https:\/\/www.inognicasonessunrimorso.org\/blog\/author\/carlo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Materiali convegno: Comitato Internazionalista Alexis Castillo - In ogni caso nessun rimorso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/","og_locale":"it_IT","og_type":"article","og_title":"Materiali convegno: Comitato Internazionalista Alexis Castillo - In ogni caso nessun rimorso","og_description":"La fase attuale della crisi multidimensionale, strutturale e sistemica del modo di produzione capitalistico \u00e8 attraversata, su scala planetaria, da diversi conflitti -guerreggiati e non &#8211; solo apparentemente scollegati tra loro. Sono la forma concreta, con discontinuit\u00e0 geografica e spaziale, che assume la III Guerra Mondiale in corso. E\u2019 il modo di essere del capitalismo&hellip;&nbsp;Leggi tutto &raquo;Materiali convegno: Comitato Internazionalista Alexis Castillo","og_url":"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/","og_site_name":"In ogni caso nessun rimorso","article_published_time":"2026-04-15T15:35:14+00:00","article_modified_time":"2026-07-15T15:35:27+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/www.inognicasonessunrimorso.org\/blog\/wp-content\/uploads\/sites\/3\/2026\/07\/COPERTINA.jpeg","type":"image\/jpeg"}],"author":"carlo","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"carlo","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/","url":"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/","name":"Materiali convegno: Comitato Internazionalista Alexis Castillo - In ogni caso nessun rimorso","isPartOf":{"@id":"https:\/\/www.inognicasonessunrimorso.org\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/#primaryimage"},"image":{"@id":"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.inognicasonessunrimorso.org\/blog\/wp-content\/uploads\/sites\/3\/2026\/07\/COPERTINA.jpeg","datePublished":"2026-04-15T15:35:14+00:00","dateModified":"2026-07-15T15:35:27+00:00","author":{"@id":"https:\/\/www.inognicasonessunrimorso.org\/blog\/#\/schema\/person\/12bbdd71594a9993b4141453c7197202"},"breadcrumb":{"@id":"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/#primaryimage","url":"https:\/\/www.inognicasonessunrimorso.org\/blog\/wp-content\/uploads\/sites\/3\/2026\/07\/COPERTINA.jpeg","contentUrl":"https:\/\/www.inognicasonessunrimorso.org\/blog\/wp-content\/uploads\/sites\/3\/2026\/07\/COPERTINA.jpeg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/www.inognicasonessunrimorso.org\/blog\/2026\/04\/15\/materiali-convegno-comitato-internazionalista-alexis-castillo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.inognicasonessunrimorso.org\/blog\/"},{"@type":"ListItem","position":2,"name":"Materiali convegno: Comitato Internazionalista Alexis Castillo"}]},{"@type":"WebSite","@id":"https:\/\/www.inognicasonessunrimorso.org\/blog\/#website","url":"https:\/\/www.inognicasonessunrimorso.org\/blog\/","name":"In ogni caso nessun rimorso","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inognicasonessunrimorso.org\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.inognicasonessunrimorso.org\/blog\/#\/schema\/person\/12bbdd71594a9993b4141453c7197202","name":"carlo","url":"https:\/\/www.inognicasonessunrimorso.org\/blog\/author\/carlo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.inognicasonessunrimorso.org\/blog\/wp-json\/wp\/v2\/posts\/1776"}],"collection":[{"href":"https:\/\/www.inognicasonessunrimorso.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inognicasonessunrimorso.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inognicasonessunrimorso.org\/blog\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inognicasonessunrimorso.org\/blog\/wp-json\/wp\/v2\/comments?post=1776"}],"version-history":[{"count":1,"href":"https:\/\/www.inognicasonessunrimorso.org\/blog\/wp-json\/wp\/v2\/posts\/1776\/revisions"}],"predecessor-version":[{"id":1777,"href":"https:\/\/www.inognicasonessunrimorso.org\/blog\/wp-json\/wp\/v2\/posts\/1776\/revisions\/1777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inognicasonessunrimorso.org\/blog\/wp-json\/wp\/v2\/media\/1702"}],"wp:attachment":[{"href":"https:\/\/www.inognicasonessunrimorso.org\/blog\/wp-json\/wp\/v2\/media?parent=1776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inognicasonessunrimorso.org\/blog\/wp-json\/wp\/v2\/categories?post=1776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inognicasonessunrimorso.org\/blog\/wp-json\/wp\/v2\/tags?post=1776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}